{"id":10862,"date":"2017-02-23T13:33:53","date_gmt":"2017-02-23T13:33:53","guid":{"rendered":"https:\/\/www.galletaspolen.com\/?post_type=product&#038;p=10862"},"modified":"2026-08-13T09:34:22","modified_gmt":"2026-08-13T09:34:22","slug":"frutas-de-aragon-caja-3kg","status":"publish","type":"product","link":"https:\/\/www.galletaspolen.com\/en\/producto\/frutas-de-aragon-caja-3kg\/","title":{"rendered":"Aragon Fruits, Box 3Kg."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Deliciosas porciones de fruta selecta confitada, cubiertas con una crujiente y generosa capa de chocolate negro puro. El dulce m\u00e1s tradicional y emblem\u00e1tico de nuestra tierra.<\/p>","protected":false},"featured_media":17195,"template":"","meta":[],"product_brand":[],"product_cat":[111],"product_tag":[638,641,637,640,639],"class_list":["post-10862","product","type-product","status-publish","has-post-thumbnail","product_cat-productos-de-navidad","product_tag-dulce-tipico-de-zaragoza","product_tag-dulces-de-aragon","product_tag-frutas-de-aragon","product_tag-productos-de-aragon","product_tag-souvenir-zaragoza","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Frutas de Arag\u00f3n 3Kg | Dulce T\u00edpico y Artesanal de Zaragoza.<\/title>\n<meta name=\"description\" content=\"Descubre las aut\u00e9nticas Frutas de Arag\u00f3n en formato de 3Kg. Deliciosa fruta confitada artesanal ba\u00f1ada en chocolate negro. El dulce t\u00edpico de Zaragoza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.galletaspolen.com\/en\/product-2\/frutas-de-aragon-caja-3kg\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frutas de Arag\u00f3n 3Kg | Dulce T\u00edpico y Artesanal de Zaragoza.\" \/>\n<meta property=\"og:description\" content=\"Descubre las aut\u00e9nticas Frutas de Arag\u00f3n en formato de 3Kg. Deliciosa fruta confitada artesanal ba\u00f1ada en chocolate negro. El dulce t\u00edpico de Zaragoza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.galletaspolen.com\/en\/product-2\/frutas-de-aragon-caja-3kg\/\" \/>\n<meta property=\"og:site_name\" content=\"Galletas Polen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-13T09:34:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2017\/02\/frutas-de-aragon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/producto\\\/frutas-de-aragon-caja-3kg\\\/\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/producto\\\/frutas-de-aragon-caja-3kg\\\/\",\"name\":\"Frutas de Arag\u00f3n 3Kg | Dulce T\u00edpico y Artesanal de Zaragoza.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/producto\\\/frutas-de-aragon-caja-3kg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/producto\\\/frutas-de-aragon-caja-3kg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/frutas-de-aragon.png\",\"datePublished\":\"2017-02-23T13:33:53+00:00\",\"dateModified\":\"2026-08-13T09:34:22+00:00\",\"description\":\"Descubre las aut\u00e9nticas Frutas de Arag\u00f3n en formato de 3Kg. Deliciosa fruta confitada artesanal ba\u00f1ada en chocolate negro. El dulce t\u00edpico de Zaragoza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/producto\\\/frutas-de-aragon-caja-3kg\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.galletaspolen.com\\\/producto\\\/frutas-de-aragon-caja-3kg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/producto\\\/frutas-de-aragon-caja-3kg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/frutas-de-aragon.png\",\"contentUrl\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/frutas-de-aragon.png\",\"width\":1080,\"height\":1080,\"caption\":\"frutas de arag\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/producto\\\/frutas-de-aragon-caja-3kg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.galletaspolen.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La tienda de galletas\",\"item\":\"https:\\\/\\\/www.galletaspolen.com\\\/la-tienda-de-galletas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Frutas de Arag\u00f3n, Caja 3Kg.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#website\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/\",\"name\":\"Galletas Polen\",\"description\":\"Productos artesanales y autenticos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.galletaspolen.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frutas de Arag\u00f3n 3Kg | Dulce T\u00edpico y Artesanal de Zaragoza.","description":"Descubre las aut\u00e9nticas Frutas de Arag\u00f3n en formato de 3Kg. Deliciosa fruta confitada artesanal ba\u00f1ada en chocolate negro. El dulce t\u00edpico de Zaragoza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.galletaspolen.com\/en\/product-2\/frutas-de-aragon-caja-3kg\/","og_locale":"en_GB","og_type":"article","og_title":"Frutas de Arag\u00f3n 3Kg | Dulce T\u00edpico y Artesanal de Zaragoza.","og_description":"Descubre las aut\u00e9nticas Frutas de Arag\u00f3n en formato de 3Kg. Deliciosa fruta confitada artesanal ba\u00f1ada en chocolate negro. El dulce t\u00edpico de Zaragoza.","og_url":"https:\/\/www.galletaspolen.com\/en\/product-2\/frutas-de-aragon-caja-3kg\/","og_site_name":"Galletas Polen","article_modified_time":"2026-08-13T09:34:22+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2017\/02\/frutas-de-aragon.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.galletaspolen.com\/producto\/frutas-de-aragon-caja-3kg\/","url":"https:\/\/www.galletaspolen.com\/producto\/frutas-de-aragon-caja-3kg\/","name":"Frutas de Arag\u00f3n 3Kg | Dulce T\u00edpico y Artesanal de Zaragoza.","isPartOf":{"@id":"https:\/\/www.galletaspolen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.galletaspolen.com\/producto\/frutas-de-aragon-caja-3kg\/#primaryimage"},"image":{"@id":"https:\/\/www.galletaspolen.com\/producto\/frutas-de-aragon-caja-3kg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2017\/02\/frutas-de-aragon.png","datePublished":"2017-02-23T13:33:53+00:00","dateModified":"2026-08-13T09:34:22+00:00","description":"Descubre las aut\u00e9nticas Frutas de Arag\u00f3n en formato de 3Kg. Deliciosa fruta confitada artesanal ba\u00f1ada en chocolate negro. El dulce t\u00edpico de Zaragoza.","breadcrumb":{"@id":"https:\/\/www.galletaspolen.com\/producto\/frutas-de-aragon-caja-3kg\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.galletaspolen.com\/producto\/frutas-de-aragon-caja-3kg\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.galletaspolen.com\/producto\/frutas-de-aragon-caja-3kg\/#primaryimage","url":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2017\/02\/frutas-de-aragon.png","contentUrl":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2017\/02\/frutas-de-aragon.png","width":1080,"height":1080,"caption":"frutas de arag\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.galletaspolen.com\/producto\/frutas-de-aragon-caja-3kg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.galletaspolen.com\/"},{"@type":"ListItem","position":2,"name":"La tienda de galletas","item":"https:\/\/www.galletaspolen.com\/la-tienda-de-galletas\/"},{"@type":"ListItem","position":3,"name":"Frutas de Arag\u00f3n, Caja 3Kg."}]},{"@type":"WebSite","@id":"https:\/\/www.galletaspolen.com\/#website","url":"https:\/\/www.galletaspolen.com\/","name":"Polen biscuits","description":"Artisan and authentic products","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.galletaspolen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/product\/10862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/media\/17195"}],"wp:attachment":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/media?parent=10862"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/product_brand?post=10862"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/product_cat?post=10862"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/product_tag?post=10862"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}