{"id":12435,"date":"2020-02-14T13:13:31","date_gmt":"2020-02-14T13:13:31","guid":{"rendered":"https:\/\/www.galletaspolen.com\/?p=12435"},"modified":"2020-02-14T13:36:51","modified_gmt":"2020-02-14T13:36:51","slug":"valentines-day","status":"publish","type":"post","link":"https:\/\/www.galletaspolen.com\/en\/san-valentin\/","title":{"rendered":"Valentine's Day, say it with Cookies, I love you!"},"content":{"rendered":"<p>Una de las fechas TOP en el regalo de galletas personalizadas a lo largo del a\u00f1o, \u00a1<strong>Es San Valent\u00edn<\/strong>! El famoso d\u00eda de los enamorad@s es una gran excusa para darle un toque dulce a un \u00a1Te quiero!<\/p>\n<p><strong>D\u00eda universal del amor y la afectividad<\/strong>, no solo es un d\u00eda para celebrar con tu pareja, es un d\u00eda que puede servir de excusa para decirle a tu madre, padre, abuela, hermano&#8230; \u00a1Te quiero mucho! Es la festividad de origen cristiano que cada a\u00f1o se celebra el 14 de febrero.<\/p>\n<blockquote><p><em>Desde Galletas Polen desde hace a\u00f1os es una costumbre recibir encargas a domicilio para este d\u00eda, encargos que se acompa\u00f1an con el cl\u00e1sico ramo de 12 rosas rojas.<\/em><\/p><\/blockquote>\n<h2 style=\"text-align: center;\"><span style=\"color: #ff9900;\">\u00a1Feliz d\u00eda de San Valent\u00edn!<\/span><\/h2>\n<p>Para nosotros es muy importante acompa\u00f1aros en los <strong>momentos especiales<\/strong>, momentos en los que quer\u00e9is compartir vuestros sentimientos y vivir experiencias inolvidables.<\/p>\n<p><strong>En Espa\u00f1a San Valent\u00edn<\/strong> empez\u00f3 como una iniciativa para incentivar el consumo, la compra de regalos en fechas puntuales. Una fecha pr\u00f3xima al comienzo del a\u00f1o (cl\u00e1sica cuesta de enero) que active el consumo de los espa\u00f1oles. Desde mediados del siglo 20, los grandes almacenes <strong>Galer\u00edas Preciados<\/strong> introdujeron esta fiesta en sus fechas de promociones.<\/p>\n<blockquote><p><em>El famoso d\u00eda de los enamorados viene del Imperio Romano, donde se hizo famoso un sacerdote que casaba en secreto a los j\u00f3venes. Una \u00e9poca en la que desafiaba al emperador que hab\u00eda prohibido la celebraci\u00f3n del matrimonio.<\/em><\/p><\/blockquote>\n<p>Hay dos regalos habituales en estas fechas, las<strong> rosas y bombones<\/strong>. Concretamente en la tienda de Galletas Polen lo m\u00e1s demandado son los <a href=\"https:\/\/www.galletaspolen.com\/en\/product\/caprichos-banados-caja-3-kg\/\">caprichos<\/a> ba\u00f1ados de chocolate, las <a href=\"https:\/\/www.galletaspolen.com\/en\/product\/paciencias-banadas-caja-3-kg\/\">chocolate patience<\/a> y los <a href=\"https:\/\/www.galletaspolen.com\/en\/product\/pure-chocolate-covered-wafer-rolls-box-115g\/\">cubanos de barquillo<\/a>.<\/p>\n<p><a href=\"https:\/\/www.galletaspolen.com\/en\/product\/caprichos-banados-caja-3-kg\/\"><img decoding=\"async\" class=\"wd-lazy-fade aligncenter wp-image-12441 size-large\" src=\"https:\/\/www.galletaspolen.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/caprichos-san-valentin-482x350.jpg\" alt=\"caprichos san valent\u00edn\" width=\"482\" height=\"350\" srcset=\"\" data-srcset=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/caprichos-san-valentin-482x350.jpg 482w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/caprichos-san-valentin-300x218.jpg 300w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/caprichos-san-valentin-150x109.jpg 150w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/caprichos-san-valentin-600x436.jpg 600w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/caprichos-san-valentin.jpg 688w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>Da igual lo que elijas pero piensa en 3 cosas que despierten sus sentidos. Algo que despierte el <strong>sentido del olfato<\/strong>, una flor que le transporte a alg\u00fan lugar so\u00f1ado o un recuerdo. Activa el <strong>sentido del gusto<\/strong> con un sabor que marque esa experiencia en el mapa de los d\u00edas especiales. Y termina con algo que despierte <strong>la emoci\u00f3n<\/strong>, escribe una carta, crea un v\u00eddeo, o haz algo que de alguna manera haga que esa persona se sienta tremendamente especial.<\/p>\n<p>Por un San Valent\u00edn en el que llegues al coraz\u00f3n a trav\u00e9s del est\u00f3mago, sabor, aromas y colores que conquisten una vez m\u00e1s a las personas que m\u00e1s quieres.<\/p>\n<blockquote><p><em>P.D.: Si eliges galletas, hoy es d\u00eda de darse un capricho, \u00a1Apuesta por el Chocolate!<\/em><\/p><\/blockquote>\n<h3 style=\"text-align: center;\"><span style=\"color: #ff9900;\">Si le dices te quiero, \u00a1Elige un sabor 100% artesanal!<\/span><\/h3>\n<p><img decoding=\"async\" class=\"wd-lazy-fade size-full wp-image-11668 aligncenter\" src=\"https:\/\/www.galletaspolen.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2018\/11\/galletas-de-calidad.png\" alt=\"Quality biscuits\" width=\"210\" height=\"146\" srcset=\"\" data-srcset=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2018\/11\/galletas-de-calidad.png 210w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2018\/11\/galletas-de-calidad-150x104.png 150w\" sizes=\"(max-width: 210px) 100vw, 210px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Una de las fechas TOP en el regalo de galletas personalizadas a lo largo del a\u00f1o, \u00a1Es San Valent\u00edn! El<\/p>","protected":false},"author":28,"featured_media":12436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[133,190],"class_list":["post-12435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-galleta","tag-galletas","tag-san-valentin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El d\u00eda de San Valent\u00edn, d\u00edselo con Galletas, \u00a1Te Quiero!<\/title>\n<meta name=\"description\" content=\"Una de las fechas TOP en el regalo de galletas personalizadas a lo largo del a\u00f1o, \u00a1Es San Valent\u00edn! El famoso d\u00eda de los enamorad@s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.galletaspolen.com\/en\/valentines-day\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El d\u00eda de San Valent\u00edn, d\u00edselo con Galletas, \u00a1Te Quiero!\" \/>\n<meta property=\"og:description\" content=\"Una de las fechas TOP en el regalo de galletas personalizadas a lo largo del a\u00f1o, \u00a1Es San Valent\u00edn! El famoso d\u00eda de los enamorad@s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.galletaspolen.com\/en\/valentines-day\/\" \/>\n<meta property=\"og:site_name\" content=\"Galletas Polen\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-14T13:13:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-14T13:36:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/san-valentin.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/\"},\"author\":{\"name\":\"Laura.\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#\\\/schema\\\/person\\\/51753261d259e330125a253a2c7d896e\"},\"headline\":\"San Valent\u00edn, d\u00edselo con Galletas, \u00a1Te Quiero!\",\"datePublished\":\"2020-02-14T13:13:31+00:00\",\"dateModified\":\"2020-02-14T13:36:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/\"},\"wordCount\":454,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/san-valentin.jpeg\",\"keywords\":[\"galletas\",\"san valent\u00edn\"],\"articleSection\":[\"Galleta\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/\",\"name\":\"El d\u00eda de San Valent\u00edn, d\u00edselo con Galletas, \u00a1Te Quiero!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/san-valentin.jpeg\",\"datePublished\":\"2020-02-14T13:13:31+00:00\",\"dateModified\":\"2020-02-14T13:36:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#\\\/schema\\\/person\\\/51753261d259e330125a253a2c7d896e\"},\"description\":\"Una de las fechas TOP en el regalo de galletas personalizadas a lo largo del a\u00f1o, \u00a1Es San Valent\u00edn! El famoso d\u00eda de los enamorad@s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/san-valentin.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/san-valentin.jpeg\",\"width\":1350,\"height\":900,\"caption\":\"san valentin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/san-valentin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.galletaspolen.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Valent\u00edn, d\u00edselo con Galletas, \u00a1Te Quiero!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#website\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/\",\"name\":\"Galletas Polen\",\"description\":\"Productos artesanales y autenticos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.galletaspolen.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#\\\/schema\\\/person\\\/51753261d259e330125a253a2c7d896e\",\"name\":\"Laura.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g\",\"caption\":\"Laura.\"},\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/en\\\/author\\\/nicanor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El d\u00eda de San Valent\u00edn, d\u00edselo con Galletas, \u00a1Te Quiero!","description":"Una de las fechas TOP en el regalo de galletas personalizadas a lo largo del a\u00f1o, \u00a1Es San Valent\u00edn! El famoso d\u00eda de los enamorad@s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.galletaspolen.com\/en\/valentines-day\/","og_locale":"en_GB","og_type":"article","og_title":"El d\u00eda de San Valent\u00edn, d\u00edselo con Galletas, \u00a1Te Quiero!","og_description":"Una de las fechas TOP en el regalo de galletas personalizadas a lo largo del a\u00f1o, \u00a1Es San Valent\u00edn! El famoso d\u00eda de los enamorad@s.","og_url":"https:\/\/www.galletaspolen.com\/en\/valentines-day\/","og_site_name":"Galletas Polen","article_published_time":"2020-02-14T13:13:31+00:00","article_modified_time":"2020-02-14T13:36:51+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/san-valentin.jpeg","type":"image\/jpeg"}],"author":"Laura.","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Laura.","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.galletaspolen.com\/san-valentin\/#article","isPartOf":{"@id":"https:\/\/www.galletaspolen.com\/san-valentin\/"},"author":{"name":"Laura.","@id":"https:\/\/www.galletaspolen.com\/#\/schema\/person\/51753261d259e330125a253a2c7d896e"},"headline":"San Valent\u00edn, d\u00edselo con Galletas, \u00a1Te Quiero!","datePublished":"2020-02-14T13:13:31+00:00","dateModified":"2020-02-14T13:36:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.galletaspolen.com\/san-valentin\/"},"wordCount":454,"commentCount":0,"image":{"@id":"https:\/\/www.galletaspolen.com\/san-valentin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/san-valentin.jpeg","keywords":["galletas","san valent\u00edn"],"articleSection":["Galleta"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.galletaspolen.com\/san-valentin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.galletaspolen.com\/san-valentin\/","url":"https:\/\/www.galletaspolen.com\/san-valentin\/","name":"El d\u00eda de San Valent\u00edn, d\u00edselo con Galletas, \u00a1Te Quiero!","isPartOf":{"@id":"https:\/\/www.galletaspolen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.galletaspolen.com\/san-valentin\/#primaryimage"},"image":{"@id":"https:\/\/www.galletaspolen.com\/san-valentin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/san-valentin.jpeg","datePublished":"2020-02-14T13:13:31+00:00","dateModified":"2020-02-14T13:36:51+00:00","author":{"@id":"https:\/\/www.galletaspolen.com\/#\/schema\/person\/51753261d259e330125a253a2c7d896e"},"description":"Una de las fechas TOP en el regalo de galletas personalizadas a lo largo del a\u00f1o, \u00a1Es San Valent\u00edn! El famoso d\u00eda de los enamorad@s.","breadcrumb":{"@id":"https:\/\/www.galletaspolen.com\/san-valentin\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.galletaspolen.com\/san-valentin\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.galletaspolen.com\/san-valentin\/#primaryimage","url":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/san-valentin.jpeg","contentUrl":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2020\/02\/san-valentin.jpeg","width":1350,"height":900,"caption":"san valentin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.galletaspolen.com\/san-valentin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.galletaspolen.com\/"},{"@type":"ListItem","position":2,"name":"San Valent\u00edn, d\u00edselo con Galletas, \u00a1Te Quiero!"}]},{"@type":"WebSite","@id":"https:\/\/www.galletaspolen.com\/#website","url":"https:\/\/www.galletaspolen.com\/","name":"Polen biscuits","description":"Artisan and authentic products","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.galletaspolen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.galletaspolen.com\/#\/schema\/person\/51753261d259e330125a253a2c7d896e","name":"Laura.","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g","caption":"Laura."},"url":"https:\/\/www.galletaspolen.com\/en\/author\/nicanor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/posts\/12435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/comments?post=12435"}],"version-history":[{"count":0,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/posts\/12435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/media\/12436"}],"wp:attachment":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/media?parent=12435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/categories?post=12435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/tags?post=12435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}