{"id":12052,"date":"2019-07-23T08:30:54","date_gmt":"2019-07-23T08:30:54","guid":{"rendered":"https:\/\/www.galletaspolen.com\/?p=12052"},"modified":"2019-07-16T08:15:15","modified_gmt":"2019-07-16T08:15:15","slug":"consumo-a-granel-para-respetar-el-medio-ambiente","status":"publish","type":"post","link":"https:\/\/www.galletaspolen.com\/en\/consumo-a-granel-para-respetar-el-medio-ambiente\/","title":{"rendered":"Bulk buying to respect the environment."},"content":{"rendered":"<p>Espa\u00f1a se encuentra entre los <strong>pa\u00edses europeos que m\u00e1s pl\u00e1stico arroja al mar<\/strong>, pensemos que de media por habitante, consumimos unas 180 bolsas de pl\u00e1stico al a\u00f1o&#8230; Hoy en d\u00eda la <strong>protecci\u00f3n de nuestro planeta<\/strong> y los efectos negativos que se visualizan en nuestras aguas, son un tema muy preocupante.<\/p>\n<blockquote>\n<p style=\"text-align: center;\">Este problema se refiere a nuestros modos de consumo.<\/p>\n<\/blockquote>\n<p>The <strong>producci\u00f3n de pl\u00e1stico<\/strong> en la \u00faltima mitad de siglo, se ha disparado, ya que casi toda la comida que consumimos viene empaquetada en materiales pl\u00e1sticos.<\/p>\n<h2 style=\"text-align: center;\"><img decoding=\"async\" class=\"wd-lazy-fade aligncenter wp-image-12058 size-large\" src=\"https:\/\/www.galletaspolen.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/consumo-a-granel-galletas-553x350.jpg\" alt=\"\" width=\"553\" height=\"350\" srcset=\"\" data-srcset=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/consumo-a-granel-galletas.jpg 553w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/consumo-a-granel-galletas-300x190.jpg 300w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/consumo-a-granel-galletas-150x95.jpg 150w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/><span style=\"color: #ff6600;\">\u00bfPor qu\u00e9 consumo a granel?<\/span><\/h2>\n<p>Desde Galletas Polen, somos conscientes de la cantidad de pl\u00e1sticos que se utilizan en los <strong>procesos de fabricaci\u00f3n<\/strong>, por ello el empaquetado de nuestros productos se basa en el cart\u00f3n.<\/p>\n<blockquote>\n<p style=\"text-align: center;\">Ahorro de pl\u00e1stico en comparaci\u00f3n con el cart\u00f3n.<\/p>\n<\/blockquote>\n<p><strong>Respetar el medio en el que vivimos<\/strong> depende de nosotros, y como fabricantes tenemos que adaptar nuestros formatos a empaquetados que no sean de un solo uso y que lleven el menor porcentaje de pl\u00e1stico posible.<\/p>\n<p>En estos momentos las <strong>cajas de productos de Galletas Polen<\/strong>, tienen un 95% de Cart\u00f3n y solo un 5% de Pl\u00e1sticos, esto quiere decir que efectivamente se puede lograr cambiar los h\u00e1bitos.<\/p>\n<blockquote>\n<p style=\"text-align: center;\">Hay que eliminar el termino de un solo uso.<\/p>\n<\/blockquote>\n<p>Todo lo envasado de usar y tirar, supone cargar nuestro planeta de pl\u00e1sticos que al final terminar\u00e1n en el mar,<em><span style=\"color: #ff6600;\"> \u00a1Cambiemos antes de que sea tarde!<\/span><\/em><\/p>\n<p>Una de las se\u00f1ales, entre las cuales puedes saber si una empresa se preocupa por el <strong>reciclaje<\/strong>, es comprobando la certificaci\u00f3n de reciclado homologado <strong>Ecoembes<\/strong>. En nuestra f\u00e1brica contamos con la\u00a0<strong>homologaci\u00f3n<\/strong> de empresas recuperadores y recicladoras.<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #ff6600;\">Respetar y cuidar el entorno en el que vivimos.<\/span><\/h3>\n<p>Pero no basta con<strong> cumplir la certificaci\u00f3n<\/strong>, en nuestra opini\u00f3n, hay que ir m\u00e1s all\u00e1. Tratando como un objetivo m\u00e1s en el departamento de I+D, la reducci\u00f3n d\u00eda a d\u00eda del uso de pl\u00e1sticos.<\/p>\n<p>No basta con cumplir con los requisitos de un certificado, tenemos que asegurarnos de que nuestra actividad se desarrolla dentro del <strong>m\u00e1ximo respeto al medio ambiente<\/strong>.<\/p>\n<p>Adem\u00e1s no solo afecta al medio en el que vivimos, tambi\u00e9n nos afecta a nosotros. La <strong>poluci\u00f3n por pl\u00e1stico<\/strong> afecta a los terrenos, a nuestra aguas, y a los animales marinos que despu\u00e9s consumimos.<\/p>\n<p><strong>Hay que educar a los m\u00e1s peque\u00f1os<\/strong>, desde Galletas Polen creemos en la concienciaci\u00f3n de los m\u00e1s j\u00f3venes, son el futuro. Por ello hemos formado parte de muchos proyectos de <strong>respeto ecol\u00f3gico y responsabilidad<\/strong> con el medio ambiente en colegios.<\/p>\n<blockquote>\n<p style=\"text-align: center;\">Al final, el ciclo de algo que no le estamos dando la importancia que requiere, terminar\u00e1 en nuestro est\u00f3mago&#8230;<\/p>\n<\/blockquote>\n<h3 style=\"text-align: center;\">Nuestro planeta nos est\u00e1 hablando, y no le estamos escuchando.<\/h3>\n<p><img decoding=\"async\" class=\"wd-lazy-fade aligncenter wp-image-12061 size-large\" src=\"https:\/\/www.galletaspolen.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/protecci\u00f3n-medio-ambiente-525x350.jpeg\" alt=\"protecci\u00f3n medio ambiente\" width=\"525\" height=\"350\" srcset=\"\" data-srcset=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/protecci\u00f3n-medio-ambiente-525x350.jpeg 525w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/protecci\u00f3n-medio-ambiente-300x200.jpeg 300w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/protecci\u00f3n-medio-ambiente-150x100.jpeg 150w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/protecci\u00f3n-medio-ambiente-600x400.jpeg 600w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/protecci\u00f3n-medio-ambiente-768x512.jpeg 768w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/protecci\u00f3n-medio-ambiente.jpeg 1351w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Espa\u00f1a se encuentra entre los pa\u00edses europeos que m\u00e1s pl\u00e1stico arroja al mar, pensemos que de media por habitante, consumimos<\/p>","protected":false},"author":28,"featured_media":12057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[161],"tags":[162,163,164],"class_list":["post-12052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente","tag-consumo-a-granel","tag-medio-ambiente","tag-plasticos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consumo a granel para respetar el Medio Ambiente.<\/title>\n<meta name=\"description\" content=\"Espa\u00f1a entre los pa\u00edses europeos que m\u00e1s pl\u00e1stico arroja al mar, pensemos que de media por habitante, consumimos unas 180 bolsas de pl\u00e1stico al a\u00f1o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.galletaspolen.com\/en\/consumo-a-granel-para-respetar-el-medio-ambiente\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consumo a granel para respetar el Medio Ambiente.\" \/>\n<meta property=\"og:description\" content=\"Espa\u00f1a entre los pa\u00edses europeos que m\u00e1s pl\u00e1stico arroja al mar, pensemos que de media por habitante, consumimos unas 180 bolsas de pl\u00e1stico al a\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.galletaspolen.com\/en\/consumo-a-granel-para-respetar-el-medio-ambiente\/\" \/>\n<meta property=\"og:site_name\" content=\"Galletas Polen\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-23T08:30:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/medio-ambiente.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1352\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/\"},\"author\":{\"name\":\"Laura.\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#\\\/schema\\\/person\\\/51753261d259e330125a253a2c7d896e\"},\"headline\":\"Consumo a granel para respetar el Medio Ambiente.\",\"datePublished\":\"2019-07-23T08:30:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/\"},\"wordCount\":494,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/medio-ambiente.jpeg\",\"keywords\":[\"consumo a granel\",\"medio ambiente\",\"pl\u00e1sticos\"],\"articleSection\":[\"medio ambiente\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/\",\"name\":\"Consumo a granel para respetar el Medio Ambiente.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/medio-ambiente.jpeg\",\"datePublished\":\"2019-07-23T08:30:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#\\\/schema\\\/person\\\/51753261d259e330125a253a2c7d896e\"},\"description\":\"Espa\u00f1a entre los pa\u00edses europeos que m\u00e1s pl\u00e1stico arroja al mar, pensemos que de media por habitante, consumimos unas 180 bolsas de pl\u00e1stico al a\u00f1o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/medio-ambiente.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/medio-ambiente.jpeg\",\"width\":1352,\"height\":900,\"caption\":\"medio ambiente\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/consumo-a-granel-para-respetar-el-medio-ambiente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.galletaspolen.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consumo a granel para respetar el Medio Ambiente.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#website\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/\",\"name\":\"Galletas Polen\",\"description\":\"Productos artesanales y autenticos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.galletaspolen.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#\\\/schema\\\/person\\\/51753261d259e330125a253a2c7d896e\",\"name\":\"Laura.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g\",\"caption\":\"Laura.\"},\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/en\\\/author\\\/nicanor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bulk buying to respect the environment.","description":"Espa\u00f1a entre los pa\u00edses europeos que m\u00e1s pl\u00e1stico arroja al mar, pensemos que de media por habitante, consumimos unas 180 bolsas de pl\u00e1stico al a\u00f1o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.galletaspolen.com\/en\/consumo-a-granel-para-respetar-el-medio-ambiente\/","og_locale":"en_GB","og_type":"article","og_title":"Consumo a granel para respetar el Medio Ambiente.","og_description":"Espa\u00f1a entre los pa\u00edses europeos que m\u00e1s pl\u00e1stico arroja al mar, pensemos que de media por habitante, consumimos unas 180 bolsas de pl\u00e1stico al a\u00f1o.","og_url":"https:\/\/www.galletaspolen.com\/en\/consumo-a-granel-para-respetar-el-medio-ambiente\/","og_site_name":"Galletas Polen","article_published_time":"2019-07-23T08:30:54+00:00","og_image":[{"width":1352,"height":900,"url":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/medio-ambiente.jpeg","type":"image\/jpeg"}],"author":"Laura.","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Laura.","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/#article","isPartOf":{"@id":"https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/"},"author":{"name":"Laura.","@id":"https:\/\/www.galletaspolen.com\/#\/schema\/person\/51753261d259e330125a253a2c7d896e"},"headline":"Consumo a granel para respetar el Medio Ambiente.","datePublished":"2019-07-23T08:30:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/"},"wordCount":494,"commentCount":0,"image":{"@id":"https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/medio-ambiente.jpeg","keywords":["consumo a granel","medio ambiente","pl\u00e1sticos"],"articleSection":["medio ambiente"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/","url":"https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/","name":"Bulk buying to respect the environment.","isPartOf":{"@id":"https:\/\/www.galletaspolen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/#primaryimage"},"image":{"@id":"https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/medio-ambiente.jpeg","datePublished":"2019-07-23T08:30:54+00:00","author":{"@id":"https:\/\/www.galletaspolen.com\/#\/schema\/person\/51753261d259e330125a253a2c7d896e"},"description":"Espa\u00f1a entre los pa\u00edses europeos que m\u00e1s pl\u00e1stico arroja al mar, pensemos que de media por habitante, consumimos unas 180 bolsas de pl\u00e1stico al a\u00f1o.","breadcrumb":{"@id":"https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/#primaryimage","url":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/medio-ambiente.jpeg","contentUrl":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/07\/medio-ambiente.jpeg","width":1352,"height":900,"caption":"medio ambiente"},{"@type":"BreadcrumbList","@id":"https:\/\/www.galletaspolen.com\/consumo-a-granel-para-respetar-el-medio-ambiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.galletaspolen.com\/"},{"@type":"ListItem","position":2,"name":"Consumo a granel para respetar el Medio Ambiente."}]},{"@type":"WebSite","@id":"https:\/\/www.galletaspolen.com\/#website","url":"https:\/\/www.galletaspolen.com\/","name":"Polen biscuits","description":"Artisan and authentic products","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.galletaspolen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.galletaspolen.com\/#\/schema\/person\/51753261d259e330125a253a2c7d896e","name":"Laura.","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g","caption":"Laura."},"url":"https:\/\/www.galletaspolen.com\/en\/author\/nicanor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/posts\/12052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/comments?post=12052"}],"version-history":[{"count":0,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/posts\/12052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/media\/12057"}],"wp:attachment":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/media?parent=12052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/categories?post=12052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/tags?post=12052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}