{"id":11974,"date":"2019-04-30T08:30:37","date_gmt":"2019-04-30T08:30:37","guid":{"rendered":"https:\/\/www.galletaspolen.com\/?p=11974"},"modified":"2019-04-24T07:56:50","modified_gmt":"2019-04-24T07:56:50","slug":"elegir-galletas-polen","status":"publish","type":"post","link":"https:\/\/www.galletaspolen.com\/en\/elegir-galletas-polen\/","title":{"rendered":"Why"},"content":{"rendered":"<p>Si estas pensando en <strong>elegir Galletas Polen<\/strong> como fabricante, vamos a explicarte varias razones que despejar\u00e1n todas tus dudas.<\/p>\n<p>Galletas polen fue fundada en 1957, empresa de reconocida calidad en el <strong>sector de la alimentaci\u00f3n<\/strong> que distribuye sus productos tanto en Espa\u00f1a como en pa\u00edses de la CEE.<\/p>\n<p>En estos momentos nuestras instalaciones se encuentran en Zaragoza (Calle Jaime Ferr\u00e1n n\u00ba26 del Pol\u00edgono de Cogullada), un lugar perfecto para la <strong>distribuci\u00f3n a nivel nacional<\/strong>.<\/p>\n<p>The<strong> superficie de 11.000 metros cuadrados<\/strong>, cuenta con 8.000 metros cuadrados para su centro de producci\u00f3n, m\u00e1s de 3.000 metros cuadrados de almac\u00e9n, as\u00ed como centros reguladores de mercanc\u00edas en diferentes puntos del territorio nacional.<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #ff9900;\"><img decoding=\"async\" class=\"wd-lazy-fade aligncenter wp-image-11977 size-large\" src=\"https:\/\/www.galletaspolen.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/logistica-galletas-polen-525x350.jpeg\" alt=\"\" width=\"525\" height=\"350\" srcset=\"\" data-srcset=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/logistica-galletas-polen-525x350.jpeg 525w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/logistica-galletas-polen-300x200.jpeg 300w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/logistica-galletas-polen-150x100.jpeg 150w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/logistica-galletas-polen-600x400.jpeg 600w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/logistica-galletas-polen-768x512.jpeg 768w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/logistica-galletas-polen.jpeg 1350w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/>Log\u00edstica de Galletas Polen<\/span><\/h2>\n<p><strong>Red log\u00edstica y distribuci\u00f3n propia<\/strong>, para un mejor flujo de las mercanc\u00edas y atenci\u00f3n personalizada de cada cliente. Adapt\u00e1ndonos a cada nuevo punto de venta para facilitar la distribuci\u00f3n de un producto 100% artesanal.<\/p>\n<blockquote>\n<p style=\"text-align: center;\">Larga experiencia en la fabricaci\u00f3n de productos de marca blanca y MDD.<\/p>\n<\/blockquote>\n<p>Parte de la diferenciaci\u00f3n de la marca Polen, es el objetivo principal de fabricaci\u00f3n, basado al 100% en la <strong>calidad de las materias primas<\/strong> y el producto final una vez terminado. La clave est\u00e1 en la calidad y el detalle con el que se termina cada unidad.<\/p>\n<p>Todos los productos englobados en cinco \u00e1reas: <a href=\"https:\/\/www.galletaspolen.com\/en\/the-biscuit-shop\/baked-biscuits\/\">Baked biscuits<\/a>, <a href=\"https:\/\/www.galletaspolen.com\/en\/the-biscuit-shop\/farmer\/\">Boers<\/a>, <a href=\"https:\/\/www.galletaspolen.com\/en\/the-biscuit-shop\/wafer-rolls\/\">Wafer rolls<\/a>, <a href=\"https:\/\/www.galletaspolen.com\/en\/product\/frutas-de-aragon-caja-3kg\/\">Aragonese Fruits<\/a> y Bombones, pueden ir ba\u00f1ados en <strong>pure chocolate<\/strong> o con la <strong>cobertura<\/strong> acordada con el cliente.<\/p>\n<p><img decoding=\"async\" class=\"wd-lazy-fade aligncenter wp-image-11975 size-large\" src=\"https:\/\/www.galletaspolen.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/chocolate-280x350.jpeg\" alt=\"Chocolate\" width=\"280\" height=\"350\" srcset=\"\" data-srcset=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/chocolate-280x350.jpeg 280w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/chocolate-300x375.jpeg 300w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/chocolate-150x187.jpeg 150w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/chocolate-600x750.jpeg 600w, https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/chocolate.jpeg 701w\" sizes=\"(max-width: 280px) 100vw, 280px\" \/><\/p>\n<p>The <strong>coberturas de chocolate<\/strong> son de fabricaci\u00f3n propia, \u00bfQu\u00e9 significa esto? En Galletas Polen realizamos el amasado, refinado y concheo del chocolate, en nuestras instalaciones.<\/p>\n<blockquote>\n<p style=\"text-align: center;\">Producci\u00f3n diaria superior a los 2.000 Kg de Chocolate.<\/p>\n<\/blockquote>\n<p>M\u00e1s de medio siglo ayudando a satisfacer alguna necesidad, presente o futura, del mercado en el segmento de Boers.\u00a0Fabricamos tanto productos a granel, destinados a la venta por peso, como productos empaquetados para su posicionamiento en los lineales.<\/p>\n<h3><span style=\"color: #ff9900;\">Garant\u00eda de los productos de Galletas Polen<\/span><\/h3>\n<p><strong><span style=\"color: #ff9900;\"><img decoding=\"async\" class=\"emoji lazyload\" draggable=\"false\" data-src=\"https:\/\/s.w.org\/images\/core\/emoji\/11\/svg\/2714.svg\" alt=\"\u2714\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/span>Handmade biscuits<\/strong>, con materias primas de primera calidad.<\/p>\n<p><img decoding=\"async\" class=\"emoji lazyload\" draggable=\"false\" data-src=\"https:\/\/s.w.org\/images\/core\/emoji\/11\/svg\/2714.svg\" alt=\"\u2714\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>a blanket of<strong> pure chocolate<\/strong>, la cual realizamos nosotros mismos. As\u00ed obtenemos el sabor POLEN.<\/p>\n<p><img decoding=\"async\" class=\"emoji lazyload\" draggable=\"false\" data-src=\"https:\/\/s.w.org\/images\/core\/emoji\/11\/svg\/2714.svg\" alt=\"\u2714\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>The <strong>Barquillo<\/strong> conserva la <strong>Traditional recipe<\/strong> despu\u00e9s de 3 generaciones adapt\u00e1ndose a las necesidades del consumidor actual.<\/p>\n<p><strong><img decoding=\"async\" class=\"emoji lazyload\" draggable=\"false\" data-src=\"https:\/\/s.w.org\/images\/core\/emoji\/11\/svg\/2714.svg\" alt=\"\u2714\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>We export<\/strong> nuestras Galletas a otros Pa\u00edses de la CEE, Asia o EEUU.<\/p>\n<p><img decoding=\"async\" class=\"emoji lazyload\" draggable=\"false\" data-src=\"https:\/\/s.w.org\/images\/core\/emoji\/11\/svg\/2714.svg\" alt=\"\u2714\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>Galletas Polen is a recognised manufacturer of <strong>Marca Blanca, MDD<\/strong>\u00a0y productos dirigidos a la<strong> l\u00ednea de Farmacia<\/strong> y el <strong>Deporte<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"emoji lazyload\" draggable=\"false\" data-src=\"https:\/\/s.w.org\/images\/core\/emoji\/11\/svg\/2714.svg\" alt=\"\u2714\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>All products are subject to <strong>rigorous quality controls<\/strong> Based on the FSSCC22000 standard.<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #ff9900;\">Sabor artesano 100% en cada Galleta<\/span><\/h1>","protected":false},"excerpt":{"rendered":"<p>Si estas pensando en elegir Galletas Polen como fabricante, vamos a explicarte varias razones que despejar\u00e1n todas tus dudas. Galletas<\/p>","protected":false},"author":28,"featured_media":11976,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[133],"class_list":["post-11974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-galleta","tag-galletas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPor qu\u00e9 elegir Galletas Polen?<\/title>\n<meta name=\"description\" content=\"Si estas pensando en elegir Galletas Polen como fabricante, vamos a explicarte varias razones que despejar\u00e1n todas tus dudas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.galletaspolen.com\/en\/elegir-galletas-polen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 elegir Galletas Polen?\" \/>\n<meta property=\"og:description\" content=\"Si estas pensando en elegir Galletas Polen como fabricante, vamos a explicarte varias razones que despejar\u00e1n todas tus dudas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.galletaspolen.com\/en\/elegir-galletas-polen\/\" \/>\n<meta property=\"og:site_name\" content=\"Galletas Polen\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-30T08:30:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/elegir-galletas-polen.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/\"},\"author\":{\"name\":\"Laura.\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#\\\/schema\\\/person\\\/51753261d259e330125a253a2c7d896e\"},\"headline\":\"\u00bfPor qu\u00e9 elegir Galletas Polen?\",\"datePublished\":\"2019-04-30T08:30:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/\"},\"wordCount\":439,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/elegir-galletas-polen.jpeg\",\"keywords\":[\"galletas\"],\"articleSection\":[\"Galleta\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/\",\"name\":\"\u00bfPor qu\u00e9 elegir Galletas Polen?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/elegir-galletas-polen.jpeg\",\"datePublished\":\"2019-04-30T08:30:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#\\\/schema\\\/person\\\/51753261d259e330125a253a2c7d896e\"},\"description\":\"Si estas pensando en elegir Galletas Polen como fabricante, vamos a explicarte varias razones que despejar\u00e1n todas tus dudas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/elegir-galletas-polen.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.galletaspolen.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/elegir-galletas-polen.jpeg\",\"width\":1350,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/elegir-galletas-polen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.galletaspolen.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 elegir Galletas Polen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#website\",\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/\",\"name\":\"Galletas Polen\",\"description\":\"Productos artesanales y autenticos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.galletaspolen.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.galletaspolen.com\\\/#\\\/schema\\\/person\\\/51753261d259e330125a253a2c7d896e\",\"name\":\"Laura.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g\",\"caption\":\"Laura.\"},\"url\":\"https:\\\/\\\/www.galletaspolen.com\\\/en\\\/author\\\/nicanor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Why","description":"Si estas pensando en elegir Galletas Polen como fabricante, vamos a explicarte varias razones que despejar\u00e1n todas tus dudas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.galletaspolen.com\/en\/elegir-galletas-polen\/","og_locale":"en_GB","og_type":"article","og_title":"\u00bfPor qu\u00e9 elegir Galletas Polen?","og_description":"Si estas pensando en elegir Galletas Polen como fabricante, vamos a explicarte varias razones que despejar\u00e1n todas tus dudas.","og_url":"https:\/\/www.galletaspolen.com\/en\/elegir-galletas-polen\/","og_site_name":"Galletas Polen","article_published_time":"2019-04-30T08:30:37+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/elegir-galletas-polen.jpeg","type":"image\/jpeg"}],"author":"Laura.","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Laura.","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/#article","isPartOf":{"@id":"https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/"},"author":{"name":"Laura.","@id":"https:\/\/www.galletaspolen.com\/#\/schema\/person\/51753261d259e330125a253a2c7d896e"},"headline":"\u00bfPor qu\u00e9 elegir Galletas Polen?","datePublished":"2019-04-30T08:30:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/"},"wordCount":439,"commentCount":0,"image":{"@id":"https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/elegir-galletas-polen.jpeg","keywords":["galletas"],"articleSection":["Galleta"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/","url":"https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/","name":"Why","isPartOf":{"@id":"https:\/\/www.galletaspolen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/#primaryimage"},"image":{"@id":"https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/elegir-galletas-polen.jpeg","datePublished":"2019-04-30T08:30:37+00:00","author":{"@id":"https:\/\/www.galletaspolen.com\/#\/schema\/person\/51753261d259e330125a253a2c7d896e"},"description":"Si estas pensando en elegir Galletas Polen como fabricante, vamos a explicarte varias razones que despejar\u00e1n todas tus dudas.","breadcrumb":{"@id":"https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/#primaryimage","url":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/elegir-galletas-polen.jpeg","contentUrl":"https:\/\/www.galletaspolen.com\/wp-content\/uploads\/2019\/04\/elegir-galletas-polen.jpeg","width":1350,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.galletaspolen.com\/elegir-galletas-polen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.galletaspolen.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 elegir Galletas Polen?"}]},{"@type":"WebSite","@id":"https:\/\/www.galletaspolen.com\/#website","url":"https:\/\/www.galletaspolen.com\/","name":"Polen biscuits","description":"Artisan and authentic products","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.galletaspolen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.galletaspolen.com\/#\/schema\/person\/51753261d259e330125a253a2c7d896e","name":"Laura.","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96da96d87dd7a29ded6cc79233c75936a945decf457c61571ff5f2b82e97e273?s=96&d=mm&r=g","caption":"Laura."},"url":"https:\/\/www.galletaspolen.com\/en\/author\/nicanor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/posts\/11974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/comments?post=11974"}],"version-history":[{"count":0,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/posts\/11974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/media\/11976"}],"wp:attachment":[{"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/media?parent=11974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/categories?post=11974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.galletaspolen.com\/en\/wp-json\/wp\/v2\/tags?post=11974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}